{"id":6605,"date":"2026-02-26T10:14:04","date_gmt":"2026-02-26T15:14:04","guid":{"rendered":"https:\/\/nomadsofhope.com\/?page_id=6605"},"modified":"2026-02-26T13:34:18","modified_gmt":"2026-02-26T18:34:18","slug":"jadan-2026-registration-pay-by-check","status":"publish","type":"page","link":"https:\/\/nomadsofhope.com\/es\/jadan-2026-registration-pay-by-check\/","title":{"rendered":"Jadan 2026 Registration Pay By Check"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Jadan 2026 Work Trip Registration &#8211; pay by check&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][wpforms_selector form_id=&#8221;6598&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/wpforms_selector][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<div class=\"et_pb_module wpforms_selector wpforms_selector_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<style id=\"wpforms-css-vars-6598\">\n\t\t\t\t#wpforms-6598 {\n\t\t\t\t--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-6598\"><form id=\"wpforms-form-6598\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"6598\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/es\/wp-json\/wp\/v2\/pages\/6605\" data-token=\"5fe3641c5d6286a841d73bfcac4728c9\" data-token-time=\"1784078385\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/div><div class=\"wpforms-page-indicator progress\" data-indicator=\"progress\" data-indicator-color=\"#066aab\" data-scroll=\"1\" role=\"progressbar\" aria-valuenow=\"1\" aria-valuemin=\"1\" aria-valuemax=\"6\" tabindex=\"-1\"><span class=\"wpforms-page-indicator-page-title\" ><\/span><span class=\"wpforms-page-indicator-page-title-sep\" style=\"display:none;\"> - <\/span><span class=\"wpforms-page-indicator-steps\">Step <span class=\"wpforms-page-indicator-steps-current\">1<\/span> of 6<\/span><div class=\"wpforms-page-indicator-page-progress-wrap\"><div class=\"wpforms-page-indicator-page-progress\" style=\"width:16.666666666667%;background-color:#066aab\"><\/div><\/div><\/div><div class=\"wpforms-field-container\"><div class=\"wpforms-page wpforms-page-1 \" data-page=\"1\"><div id=\"wpforms-6598-field_17-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-type=\"pagebreak\" data-field-id=\"17\"><\/div>\t\t<div id=\"wpforms-6598-field_1-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"1\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-6598-field_1\" >Birth Release all<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-6598-field_1\" class=\"wpforms-field-medium\" name=\"wpforms[fields][1]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-6598-field_2-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"2\"><fieldset><legend class=\"wpforms-field-label\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-6598-field_2\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][2][first]\" aria-errormessage=\"wpforms-6598-field_2-error\" required><label for=\"wpforms-6598-field_2\" class=\"wpforms-field-sublabel after\">Nombre<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-6598-field_2-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][2][last]\" aria-errormessage=\"wpforms-6598-field_2-last-error\" required><label for=\"wpforms-6598-field_2-last\" class=\"wpforms-field-sublabel after\">Apellidos<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-6598-field_5-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-type=\"date-time\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-6598-field_5\">Date of Birth <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-6598-field_5\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][5][date]\" aria-errormessage=\"wpforms-6598-field_5-error\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-6598-field_4-container\" class=\"wpforms-field wpforms-field-address\" data-field-type=\"address\" data-field-id=\"4\"><fieldset><legend class=\"wpforms-field-label\">Address<\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div ><input type=\"text\" id=\"wpforms-6598-field_4\" class=\"wpforms-field-address-address1\" name=\"wpforms[fields][4][address1]\" aria-errormessage=\"wpforms-6598-field_4-error\" ><label for=\"wpforms-6598-field_4\" class=\"wpforms-field-sublabel after\">Address Line 1<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div ><input type=\"text\" id=\"wpforms-6598-field_4-address2\" class=\"wpforms-field-address-address2\" name=\"wpforms[fields][4][address2]\" aria-errormessage=\"wpforms-6598-field_4-address2-error\" ><label for=\"wpforms-6598-field_4-address2\" class=\"wpforms-field-sublabel after\">Address Line 2<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-6598-field_4-city\" class=\"wpforms-field-address-city\" name=\"wpforms[fields][4][city]\" aria-errormessage=\"wpforms-6598-field_4-city-error\" ><label for=\"wpforms-6598-field_4-city\" class=\"wpforms-field-sublabel after\">Ciudad<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><select id=\"wpforms-6598-field_4-state\" class=\"wpforms-field-address-state\" name=\"wpforms[fields][4][state]\" aria-errormessage=\"wpforms-6598-field_4-state-error\" ><option class=\"placeholder\" value=\"\" selected disabled>--- Select state ---<\/option><option value=\"AL\" >Alabama<\/option><option value=\"AK\" >Alaska<\/option><option value=\"AZ\" >Arizona<\/option><option value=\"AR\" >Arkansas<\/option><option value=\"CA\" >California<\/option><option value=\"CO\" >Colorado<\/option><option value=\"CT\" >Connecticut<\/option><option value=\"DE\" >Delaware<\/option><option value=\"DC\" >Distrito de Columbia<\/option><option value=\"FL\" >Florida<\/option><option value=\"GA\" >Georgia<\/option><option value=\"HI\" >Hawai<\/option><option value=\"ID\" >Idaho<\/option><option value=\"IL\" >Illinois<\/option><option value=\"IN\" >Indiana<\/option><option value=\"IA\" >Iowa<\/option><option value=\"KS\" >Kansas<\/option><option value=\"KY\" >Kentucky<\/option><option value=\"LA\" >Luisiana<\/option><option value=\"ME\" >Maine<\/option><option value=\"MD\" >Maryland<\/option><option value=\"MA\" >Massachusetts<\/option><option value=\"MI\" >M\u00edchigan<\/option><option value=\"MN\" >Minnesota<\/option><option value=\"MS\" >Misisip\u00ed<\/option><option value=\"MO\" >Misuri<\/option><option value=\"MT\" >Montana<\/option><option value=\"NE\" >Nebraska<\/option><option value=\"NV\" >Nevada<\/option><option value=\"NH\" >Nuevo Hampshire<\/option><option value=\"NJ\" >Nueva Jersey<\/option><option value=\"NM\" >Nuevo M\u00e9xico<\/option><option value=\"NY\" >Nueva York<\/option><option value=\"NC\" >Carolina del norte<\/option><option value=\"ND\" >Dakota del norte<\/option><option value=\"OH\" >Ohio<\/option><option value=\"OK\" >Oklahoma<\/option><option value=\"OR\" >Oreg\u00f3n<\/option><option value=\"PA\" >Pensilvania<\/option><option value=\"RI\" >Rhode Island<\/option><option value=\"SC\" >Carolina del Sur<\/option><option value=\"SD\" >Dakota del Sur<\/option><option value=\"TN\" >Tennessee<\/option><option value=\"TX\" >Texas<\/option><option value=\"UT\" >Utah<\/option><option value=\"VT\" >Vermont<\/option><option value=\"VA\" >Virginia<\/option><option value=\"WA\" >Washington<\/option><option value=\"WV\" >Virginia Occidental<\/option><option value=\"WI\" >Wisconsin<\/option><option value=\"WY\" >Wyoming<\/option><\/select><label for=\"wpforms-6598-field_4-state\" class=\"wpforms-field-sublabel after\">State<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-6598-field_4-postal\" class=\"wpforms-field-address-postal wpforms-masked-input\" data-inputmask-mask=\"(99999)|(99999-9999)\" data-inputmask-keepstatic=\"true\" data-rule-inputmask-incomplete=\"1\" name=\"wpforms[fields][4][postal]\" aria-errormessage=\"wpforms-6598-field_4-postal-error\" ><label for=\"wpforms-6598-field_4-postal\" class=\"wpforms-field-sublabel after\">Zip Code<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-6598-field_3-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-6598-field_3\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-6598-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" spellcheck=\"false\" aria-errormessage=\"wpforms-6598-field_3-error\" required><\/div><div id=\"wpforms-6598-field_39-container\" class=\"wpforms-field wpforms-field-phone\" data-field-type=\"phone\" data-field-id=\"39\"><label class=\"wpforms-field-label\" for=\"wpforms-6598-field_39\">Phone <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-6598-field_39\" class=\"wpforms-field-medium wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][39]\" aria-label=\"Phone\" aria-errormessage=\"wpforms-6598-field_39-error\" required><\/div><div id=\"wpforms-6598-field_6-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-conditional-trigger\" data-field-type=\"checkbox\" data-field-id=\"6\"><fieldset><legend class=\"wpforms-field-label\">Travelers Must Be 18 by July 2026 or Must be Accompanied by a Parent or Guardian <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-6598-field_6\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-6598-field_6_1\" name=\"wpforms[fields][6][]\" value=\"I will be 18 by July 2026\" aria-errormessage=\"wpforms-6598-field_6_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6598-field_6_1\">I will be 18 by July 2026<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-6598-field_6_2\" name=\"wpforms[fields][6][]\" value=\"I will not be 18 by July 2026\" aria-errormessage=\"wpforms-6598-field_6_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6598-field_6_2\">I will not be 18 by July 2026<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-6598-field_7-container\" class=\"wpforms-field wpforms-field-name wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"name\" data-field-id=\"7\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">Parent or Gaurdian Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-6598-field_7\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][7][first]\" aria-errormessage=\"wpforms-6598-field_7-error\" required><label for=\"wpforms-6598-field_7\" class=\"wpforms-field-sublabel after\">Nombre<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-6598-field_7-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][7][last]\" aria-errormessage=\"wpforms-6598-field_7-last-error\" required><label for=\"wpforms-6598-field_7-last\" class=\"wpforms-field-sublabel after\">Apellidos<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-6598-field_8-container\" class=\"wpforms-field wpforms-field-date-time wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"date-time\" data-field-id=\"8\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-6598-field_8\">Date of Birth  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-6598-field_8\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][8][date]\" aria-errormessage=\"wpforms-6598-field_8-error\" aria-describedby=\"wpforms-6598-field_8-description\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><div id=\"wpforms-6598-field_8-description\" class=\"wpforms-field-description\">Date of birth of the parent or guardian of a minor traveler<\/div><\/div><div id=\"wpforms-6598-field_9-container\" class=\"wpforms-field wpforms-field-address wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"address\" data-field-id=\"9\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">Address<\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div ><input type=\"text\" id=\"wpforms-6598-field_9\" class=\"wpforms-field-address-address1\" name=\"wpforms[fields][9][address1]\" aria-errormessage=\"wpforms-6598-field_9-error\" ><label for=\"wpforms-6598-field_9\" class=\"wpforms-field-sublabel after\">Address Line 1<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div ><input type=\"text\" id=\"wpforms-6598-field_9-address2\" class=\"wpforms-field-address-address2\" name=\"wpforms[fields][9][address2]\" aria-errormessage=\"wpforms-6598-field_9-address2-error\" ><label for=\"wpforms-6598-field_9-address2\" class=\"wpforms-field-sublabel after\">Address Line 2<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-6598-field_9-city\" class=\"wpforms-field-address-city\" name=\"wpforms[fields][9][city]\" aria-errormessage=\"wpforms-6598-field_9-city-error\" ><label for=\"wpforms-6598-field_9-city\" class=\"wpforms-field-sublabel after\">Ciudad<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><select id=\"wpforms-6598-field_9-state\" class=\"wpforms-field-address-state\" name=\"wpforms[fields][9][state]\" aria-errormessage=\"wpforms-6598-field_9-state-error\" ><option class=\"placeholder\" value=\"\" selected disabled>--- Select state ---<\/option><option value=\"AL\" >Alabama<\/option><option value=\"AK\" >Alaska<\/option><option value=\"AZ\" >Arizona<\/option><option value=\"AR\" >Arkansas<\/option><option value=\"CA\" >California<\/option><option value=\"CO\" >Colorado<\/option><option value=\"CT\" >Connecticut<\/option><option value=\"DE\" >Delaware<\/option><option value=\"DC\" >Distrito de Columbia<\/option><option value=\"FL\" >Florida<\/option><option value=\"GA\" >Georgia<\/option><option value=\"HI\" >Hawai<\/option><option value=\"ID\" >Idaho<\/option><option value=\"IL\" >Illinois<\/option><option value=\"IN\" >Indiana<\/option><option value=\"IA\" >Iowa<\/option><option value=\"KS\" >Kansas<\/option><option value=\"KY\" >Kentucky<\/option><option value=\"LA\" >Luisiana<\/option><option value=\"ME\" >Maine<\/option><option value=\"MD\" >Maryland<\/option><option value=\"MA\" >Massachusetts<\/option><option value=\"MI\" >M\u00edchigan<\/option><option value=\"MN\" >Minnesota<\/option><option value=\"MS\" >Misisip\u00ed<\/option><option value=\"MO\" >Misuri<\/option><option value=\"MT\" >Montana<\/option><option value=\"NE\" >Nebraska<\/option><option value=\"NV\" >Nevada<\/option><option value=\"NH\" >Nuevo Hampshire<\/option><option value=\"NJ\" >Nueva Jersey<\/option><option value=\"NM\" >Nuevo M\u00e9xico<\/option><option value=\"NY\" >Nueva York<\/option><option value=\"NC\" >Carolina del norte<\/option><option value=\"ND\" >Dakota del norte<\/option><option value=\"OH\" >Ohio<\/option><option value=\"OK\" >Oklahoma<\/option><option value=\"OR\" >Oreg\u00f3n<\/option><option value=\"PA\" >Pensilvania<\/option><option value=\"RI\" >Rhode Island<\/option><option value=\"SC\" >Carolina del Sur<\/option><option value=\"SD\" >Dakota del Sur<\/option><option value=\"TN\" >Tennessee<\/option><option value=\"TX\" >Texas<\/option><option value=\"UT\" >Utah<\/option><option value=\"VT\" >Vermont<\/option><option value=\"VA\" >Virginia<\/option><option value=\"WA\" >Washington<\/option><option value=\"WV\" >Virginia Occidental<\/option><option value=\"WI\" >Wisconsin<\/option><option value=\"WY\" >Wyoming<\/option><\/select><label for=\"wpforms-6598-field_9-state\" class=\"wpforms-field-sublabel after\">State<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-6598-field_9-postal\" class=\"wpforms-field-address-postal wpforms-masked-input\" data-inputmask-mask=\"(99999)|(99999-9999)\" data-inputmask-keepstatic=\"true\" data-rule-inputmask-incomplete=\"1\" name=\"wpforms[fields][9][postal]\" aria-errormessage=\"wpforms-6598-field_9-postal-error\" ><label for=\"wpforms-6598-field_9-postal\" class=\"wpforms-field-sublabel after\">Zip Code<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-6598-field_10-container\" class=\"wpforms-field wpforms-field-email wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"email\" data-field-id=\"10\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-6598-field_10\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-6598-field_10\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][10]\" spellcheck=\"false\" aria-errormessage=\"wpforms-6598-field_10-error\" required><\/div><div id=\"wpforms-6598-field_16-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-type=\"pagebreak\" data-field-id=\"16\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"1\" data-formid=\"6598\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Next<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-2  \" data-page=\"2\" style=\"display:none;\"><div id=\"wpforms-6598-field_40-container\" class=\"wpforms-field wpforms-field-divider\" data-field-type=\"divider\" data-field-id=\"40\"><h3 id=\"wpforms-6598-field_40\" aria-errormessage=\"wpforms-6598-field_40-error\">Emergency Contact<\/h3><\/div><div id=\"wpforms-6598-field_41-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"41\"><fieldset><legend class=\"wpforms-field-label\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-6598-field_41\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][41][first]\" aria-errormessage=\"wpforms-6598-field_41-error\" required><label for=\"wpforms-6598-field_41\" class=\"wpforms-field-sublabel after\">Nombre<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-6598-field_41-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][41][last]\" aria-errormessage=\"wpforms-6598-field_41-last-error\" required><label for=\"wpforms-6598-field_41-last\" class=\"wpforms-field-sublabel after\">Apellidos<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-6598-field_43-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"43\"><label class=\"wpforms-field-label\" for=\"wpforms-6598-field_43\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-6598-field_43\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][43]\" spellcheck=\"false\" aria-errormessage=\"wpforms-6598-field_43-error\" required><\/div><div id=\"wpforms-6598-field_44-container\" class=\"wpforms-field wpforms-field-phone\" data-field-type=\"phone\" data-field-id=\"44\"><label class=\"wpforms-field-label\" for=\"wpforms-6598-field_44\">Phone <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-6598-field_44\" class=\"wpforms-field-medium wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][44]\" aria-label=\"Phone\" aria-errormessage=\"wpforms-6598-field_44-error\" required><\/div><div id=\"wpforms-6598-field_42-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"42\"><label class=\"wpforms-field-label\" for=\"wpforms-6598-field_42\">Relationship  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-6598-field_42\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][42]\" aria-errormessage=\"wpforms-6598-field_42-error\" aria-describedby=\"wpforms-6598-field_42-description\" required><div id=\"wpforms-6598-field_42-description\" class=\"wpforms-field-description\">Please describe your relationship to the emergency contact<\/div><\/div><div id=\"wpforms-6598-field_45-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-type=\"pagebreak\" data-field-id=\"45\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"2\" data-formid=\"6598\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Next<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-3  \" data-page=\"3\" style=\"display:none;\"><div id=\"wpforms-6598-field_14-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"14\"><div id=\"wpforms-6598-field_14\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-6598-field_14-error\"><h4>Jadan Work Trip Description<\/h4>\n<p>Trip Details<br \/>\nLocation: Cuenca, Ecuador<br \/>\nDates: July 24 - August 3, 2026<br \/>\nType: Cultural immersion, community projects, and family home-stay.<\/p>\n<p>Registration Requirements (Due April 1, 2026)<br \/>\n- Valid passport through February 2027<br \/>\n- Color copy of passport and one additional photo ID<br \/>\n- Proof of medical insurance valid in Ecuador<br \/>\n- Completed Nomads of Hope Health Profile<br \/>\n- Completed Nomads of Hope Volunteer Release &amp; Waiver<br \/>\n- Trip cancellation insurance<\/p>\n<p>Payment Schedule<br \/>\nTotal Trip Cost: $1,500.00<\/p>\n<p>Total due by April 1, 2026<br \/>\nIncluded in the $1,500.00 cost is a $500.00 non-refundable deposit<\/p>\n<p>Trip Inclusions<br \/>\n- Cuenca Airport\/Bus Terminal pickup and transportation to lodging<br \/>\n- All lodging and meals during project<br \/>\n- Nomads of Hope T-Shirt<br \/>\n- All group activities in Cuenca<br \/>\n- All planned group activities on after-trip<\/p>\n<p>Not Included<br \/>\n- Souvenirs<br \/>\n- Extra activities on after-trip<br \/>\n- Extra food and drinks<br \/>\n- Medical expenses<\/p>\n<p>Important Notice<br \/>\nThe planned itinerary may change based on unforeseen circumstances including weather, political conditions, and local partner capabilities. Nomads of Hope will communicate itinerary changes promptly.<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-6598-field_23-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"23\"><fieldset><legend class=\"wpforms-field-label\">I have read and understand the trip description <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-6598-field_23\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-6598-field_23_1\" name=\"wpforms[fields][23][]\" value=\"Yes\" aria-errormessage=\"wpforms-6598-field_23_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6598-field_23_1\">Yes<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-6598-field_24-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"24\"><fieldset><legend class=\"wpforms-field-label\">I meet all of the requirements <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-6598-field_24\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-6598-field_24_1\" name=\"wpforms[fields][24][]\" value=\"Yes\" aria-errormessage=\"wpforms-6598-field_24_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6598-field_24_1\">Yes<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-6598-field_25-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"25\"><fieldset><legend class=\"wpforms-field-label\">I understand that the trip itinerary is subject to change <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-6598-field_25\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-6598-field_25_1\" name=\"wpforms[fields][25][]\" value=\"Yes\" aria-errormessage=\"wpforms-6598-field_25_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6598-field_25_1\">Yes<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-6598-field_34-container\" class=\"wpforms-field wpforms-field-radio\" data-field-type=\"radio\" data-field-id=\"34\"><fieldset><legend class=\"wpforms-field-label\">Please Select Your After-Trip Choice<\/legend><ul id=\"wpforms-6598-field_34\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-6598-field_34_1\" name=\"wpforms[fields][34]\" value=\"Caja Hiking Adventure\" aria-errormessage=\"wpforms-6598-field_34_1-error\" aria-describedby=\"wpforms-6598-field_34-description\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6598-field_34_1\">Caja Hiking Adventure<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-6598-field_34_2\" name=\"wpforms[fields][34]\" value=\"Cuenca Free Time with Spa\" aria-errormessage=\"wpforms-6598-field_34_2-error\" aria-describedby=\"wpforms-6598-field_34-description\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6598-field_34_2\">Cuenca Free Time with Spa<\/label><\/li><\/ul><div id=\"wpforms-6598-field_34-description\" class=\"wpforms-field-description\">We need to gage interest in each of the options for planning. Your choice can be changed later. <\/div><\/fieldset><\/div><div id=\"wpforms-6598-field_19-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-type=\"pagebreak\" data-field-id=\"19\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><button class=\"wpforms-page-button wpforms-page-prev wpforms-disabled\"\n\t\t\t\t\tdata-action=\"prev\" data-page=\"3\" data-formid=\"6598\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Previous<\/button><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"3\" data-formid=\"6598\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Next<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-4  \" data-page=\"4\" style=\"display:none;\"><div id=\"wpforms-6598-field_20-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"20\"><div id=\"wpforms-6598-field_20\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-6598-field_20-error\"><h4>Refund Policy<\/h4>\n<div class=\"et_pb_toggle_content clearfix\">\n<p>Refund Policy for Nomads of Hope Building Projects Trips<\/p>\n<p>\u2022 Total trip cost: $1,500.00<\/p>\n<p>\u2022 Required deposit: $500.00 (non-refundable)<\/p>\n<p>\u2022 If Nomads of Hope cancels the trip:<br \/>\n\u2013 All payments will be refunded in full, including the deposit<\/p>\n<p>\u2022 If traveler cancels:<br \/>\n\u2013 Cancellation must be requested via email<br \/>\n\u2013 If cancelled 30 days or more before the trip start date:<br \/>\n* All payments will be refunded minus the $500.00 non-refundable deposit<br \/>\n\u2013 If cancelled less than 30 days before the trip start date:<br \/>\n* No refunds will be given<\/p>\n<p>\u2022 No exceptions will be made to this policy unless otherwise stated by Nomads of Hope<\/p>\n<p>Please note: It is the traveler\u2019s responsibility to ensure their cancellation request is received and acknowledged by Nomads of Hope within the specified time frame to be eligible for a partial refund.<\/p>\n<\/div>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-6598-field_22-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"22\"><fieldset><legend class=\"wpforms-field-label\">I have read and agree with the Refund Policy <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-6598-field_22\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-6598-field_22_1\" name=\"wpforms[fields][22][]\" value=\"Agree\" aria-errormessage=\"wpforms-6598-field_22_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6598-field_22_1\">Agree<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-6598-field_21-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-type=\"pagebreak\" data-field-id=\"21\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><button class=\"wpforms-page-button wpforms-page-prev wpforms-disabled\"\n\t\t\t\t\tdata-action=\"prev\" data-page=\"4\" data-formid=\"6598\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Previous<\/button><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"4\" data-formid=\"6598\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Next<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-5  \" data-page=\"5\" style=\"display:none;\"><div id=\"wpforms-6598-field_26-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"26\"><div id=\"wpforms-6598-field_26\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-6598-field_26-error\"><h4>Volunteer Release &amp; Waiver<\/h4>\n<p>VOLUNTEER RELEASE AND WAIVER<br \/>\nIMPORTANT: THIS IS A LEGAL DOCUMENT AFFECTING YOUR LEGAL RIGHTS - READ CAREFULLY<\/p>\n<p>Activity: Ecuador Service Project Trip<\/p>\n<p>I, the Volunteer, execute this Release in favor of Nomads of Hope, Inc. (Massachusetts nonprofit corporation), its directors, officers, employees, and agents (collectively \"Nomads\").<\/p>\n<p>Understanding of Activities<br \/>\nThe Activities may include:<br \/>\n- Pre-trip and post-trip activities<br \/>\n- Community service activities<br \/>\n- Basic home repair and construction<br \/>\n- Educational and recreational activities<br \/>\n- Domestic and international travel<\/p>\n<p>Terms and Conditions<\/p>\n<p>Release and Waiver<br \/>\n- Volunteer releases Nomads from all liability, claims, and demands<br \/>\n- Covers bodily injury, illness, death, property damage\/loss<br \/>\n- Includes incidents caused by Nomads' negligence<br \/>\n- Nomads assumes no obligation for financial or other assistance<\/p>\n<p>Medical Treatment<br \/>\n- Volunteer releases Nomads from claims regarding any medical treatment\/services<br \/>\n- Volunteer must provide proof of medical insurance<br \/>\n- Nomads does not provide medical insurance<\/p>\n<p>Risk Assumption<br \/>\nVolunteer assumes all risks of injury\/harm and releases Nomads from liability for:<br \/>\n- Injury<br \/>\n- Illness<br \/>\n- Death<br \/>\n- Property damage<\/p>\n<p>Photographic Release<br \/>\nVolunteer grants Nomads all rights to:<br \/>\n- Photographic images<br \/>\n- Video recordings<br \/>\n- Audio recordings<br \/>\n- Associated royalties\/proceeds<\/p>\n<p>Legal Provisions<br \/>\n- Release governed by Massachusetts law<br \/>\n- Invalid clauses will not affect remaining provisions<br \/>\n- Release intended to be as broad as legally permitted<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-6598-field_27-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"27\"><fieldset><legend class=\"wpforms-field-label\">Volunteer Release &amp; Waiver <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-6598-field_27\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-6598-field_27_1\" name=\"wpforms[fields][27][]\" value=\"By checking this box, I confirm that I have read, understand, and agree to the above provisions.\" aria-errormessage=\"wpforms-6598-field_27_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6598-field_27_1\">By checking this box, I confirm that I have read, understand, and agree to the above provisions.<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-6598-field_33-container\" class=\"wpforms-field wpforms-field-signature\" data-field-type=\"signature\" data-field-id=\"33\"><label class=\"wpforms-field-label\" for=\"wpforms-6598-field_33\">Signature <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-6598-field_33\" class=\"wpforms-signature-input wpforms-screen-reader-element wpforms-field-required\" data-is-wrapped-field=\"1\" name=\"wpforms[fields][33]\" autocomplete=\"off\" inputmode=\"none\" aria-errormessage=\"wpforms-6598-field_33-error\" required><div class=\"wpforms-signature-wrap wpforms-field-row wpforms-field-large\"><canvas class=\"wpforms-signature-canvas\" id=\"wpforms-6598-field_33-signature\" data-color=\"#000000\"><\/canvas><div class=\"wpforms-signature-clear\" title=\"Clear Signature\" tabindex=\"0\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1em\" height=\"1em\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 1536 1536\">\n\t\t\t\t\t<path fill=\"var( --wpforms-field-text-color, rgba(0, 0, 0, 0.25) )\" d=\"M1149 994q0-26-19-45L949 768l181-181q19-19 19-45q0-27-19-46l-90-90q-19-19-46-19q-26 0-45 19L768 587L587 406q-19-19-45-19q-27 0-46 19l-90 90q-19 19-19 46q0 26 19 45l181 181l-181 181q-19 19-19 45q0 27 19 46l90 90q19 19 46 19q26 0 45-19l181-181l181 181q19 19 45 19q27 0 46-19l90-90q19-19 19-46zm387-226q0 209-103 385.5T1153.5 1433T768 1536t-385.5-103T103 1153.5T0 768t103-385.5T382.5 103T768 0t385.5 103T1433 382.5T1536 768z\"\/>\n\t\t\t\t<\/svg>\n\t\t\t\t<div class=\"wpforms-signature-clear-caption\">Clear Signature<\/div>\n\t\t\t<\/div><\/div><\/div><div id=\"wpforms-6598-field_28-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-type=\"pagebreak\" data-field-id=\"28\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"5\" data-formid=\"6598\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Next<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-6 last \" data-page=\"6\" style=\"display:none;\"><div id=\"wpforms-6598-field_38-container\" class=\"wpforms-field wpforms-field-content\" data-field-type=\"content\" data-field-id=\"38\"><div id=\"wpforms-6598-field_38\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-6598-field_38-error\"><h4>Payment Instructions<\/h4>\n<p>$1,500.00 Due by April 1, 2026<br \/>\nIncluded in this payment is a $500.00 non-refundable deposit. (see refund policy)<\/p>\n<p>Make Check Payable To:<br \/>\nNomads of Hope, Inc.<\/p>\n<p>Mail To:<br \/>\nNomads of Hope<br \/>\n238 State Avenue<br \/>\nPalmer, MA 01069<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-6598-field_18-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-type=\"pagebreak\" data-field-id=\"18\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><button class=\"wpforms-page-button wpforms-page-prev wpforms-disabled\"\n\t\t\t\t\tdata-action=\"prev\" data-page=\"6\" data-formid=\"6598\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Previous<\/button><\/div><\/div><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-6598-field_1-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-6598-field_1-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-6598-field_1-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-hcaptcha\" style=\"display:none;\"><div class=\"h-captcha\" data-sitekey=\"a2c6438a-809a-498a-bba0-abbe235c6b62\"><\/div><input type=\"text\" name=\"g-recaptcha-hidden\" class=\"wpforms-recaptcha-hidden\" style=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\" data-rule-hcaptcha=\"1\"><\/div><div class=\"wpforms-submit-container\" style=\"display:none;\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"6598\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/nomadsofhope.com\/es\/wp-json\/wp\/v2\/pages\/6605\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-6598\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nomadsofhope.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Cargando\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-6605","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jadan 2026 Registration Pay By Check - Nomads of Hope<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nomadsofhope.com\/es\/jadan-2026-registration-pay-by-check\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jadan 2026 Registration Pay By Check - Nomads of Hope\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nomadsofhope.com\/es\/jadan-2026-registration-pay-by-check\/\" \/>\n<meta property=\"og:site_name\" content=\"Nomads of Hope\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-26T18:34:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"[wpforms_selector form_id=&quot;6598&quot; _builder_version=&quot;4.27.5&quot; _module_preset=&quot;default&quot; global_colors_info=&quot;{}&quot;][\/wpforms_selector]\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nomadsofhope.com\\\/jadan-2026-registration-pay-by-check\\\/\",\"url\":\"https:\\\/\\\/nomadsofhope.com\\\/jadan-2026-registration-pay-by-check\\\/\",\"name\":\"Jadan 2026 Registration Pay By Check - Nomads of Hope\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nomadsofhope.com\\\/#website\"},\"datePublished\":\"2026-02-26T15:14:04+00:00\",\"dateModified\":\"2026-02-26T18:34:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nomadsofhope.com\\\/jadan-2026-registration-pay-by-check\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nomadsofhope.com\\\/jadan-2026-registration-pay-by-check\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nomadsofhope.com\\\/jadan-2026-registration-pay-by-check\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nomadsofhope.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jadan 2026 Registration Pay By Check\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nomadsofhope.com\\\/#website\",\"url\":\"https:\\\/\\\/nomadsofhope.com\\\/\",\"name\":\"Nomads of Hope\",\"description\":\"follow your heart  change the world\",\"publisher\":{\"@id\":\"https:\\\/\\\/nomadsofhope.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nomadsofhope.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nomadsofhope.com\\\/#organization\",\"name\":\"Nomads of Hope\",\"url\":\"https:\\\/\\\/nomadsofhope.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nomadsofhope.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nomadsofhope.com\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/mobile-logo-e1503621162214.png\",\"contentUrl\":\"https:\\\/\\\/nomadsofhope.com\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/mobile-logo-e1503621162214.png\",\"width\":59,\"height\":58,\"caption\":\"Nomads of Hope\"},\"image\":{\"@id\":\"https:\\\/\\\/nomadsofhope.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jadan 2026 Registration Pay By Check - Nomads of Hope","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nomadsofhope.com\/es\/jadan-2026-registration-pay-by-check\/","og_locale":"es_ES","og_type":"article","og_title":"Jadan 2026 Registration Pay By Check - Nomads of Hope","og_url":"https:\/\/nomadsofhope.com\/es\/jadan-2026-registration-pay-by-check\/","og_site_name":"Nomads of Hope","article_modified_time":"2026-02-26T18:34:18+00:00","twitter_card":"summary_large_image","twitter_description":"[wpforms_selector form_id=\"6598\" _builder_version=\"4.27.5\" _module_preset=\"default\" global_colors_info=\"{}\"][\/wpforms_selector]","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nomadsofhope.com\/jadan-2026-registration-pay-by-check\/","url":"https:\/\/nomadsofhope.com\/jadan-2026-registration-pay-by-check\/","name":"Jadan 2026 Registration Pay By Check - Nomads of Hope","isPartOf":{"@id":"https:\/\/nomadsofhope.com\/#website"},"datePublished":"2026-02-26T15:14:04+00:00","dateModified":"2026-02-26T18:34:18+00:00","breadcrumb":{"@id":"https:\/\/nomadsofhope.com\/jadan-2026-registration-pay-by-check\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nomadsofhope.com\/jadan-2026-registration-pay-by-check\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nomadsofhope.com\/jadan-2026-registration-pay-by-check\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nomadsofhope.com\/"},{"@type":"ListItem","position":2,"name":"Jadan 2026 Registration Pay By Check"}]},{"@type":"WebSite","@id":"https:\/\/nomadsofhope.com\/#website","url":"https:\/\/nomadsofhope.com\/","name":"N\u00f3madas de Esperanza","description":"follow your heart  change the world","publisher":{"@id":"https:\/\/nomadsofhope.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nomadsofhope.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nomadsofhope.com\/#organization","name":"N\u00f3madas de Esperanza","url":"https:\/\/nomadsofhope.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nomadsofhope.com\/#\/schema\/logo\/image\/","url":"https:\/\/nomadsofhope.com\/wp-content\/uploads\/2017\/08\/mobile-logo-e1503621162214.png","contentUrl":"https:\/\/nomadsofhope.com\/wp-content\/uploads\/2017\/08\/mobile-logo-e1503621162214.png","width":59,"height":58,"caption":"Nomads of Hope"},"image":{"@id":"https:\/\/nomadsofhope.com\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/nomadsofhope.com\/es\/wp-json\/wp\/v2\/pages\/6605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nomadsofhope.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nomadsofhope.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nomadsofhope.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nomadsofhope.com\/es\/wp-json\/wp\/v2\/comments?post=6605"}],"version-history":[{"count":3,"href":"https:\/\/nomadsofhope.com\/es\/wp-json\/wp\/v2\/pages\/6605\/revisions"}],"predecessor-version":[{"id":6631,"href":"https:\/\/nomadsofhope.com\/es\/wp-json\/wp\/v2\/pages\/6605\/revisions\/6631"}],"wp:attachment":[{"href":"https:\/\/nomadsofhope.com\/es\/wp-json\/wp\/v2\/media?parent=6605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}